{
    "id": 875,
    "date": "2022-09-22T23:10:59",
    "date_gmt": "2022-09-22T21:10:59",
    "guid": {
        "rendered": "https:\/\/ingrilspa.com\/?page_id=875"
    },
    "modified": "2022-09-29T22:12:46",
    "modified_gmt": "2022-09-29T20:12:46",
    "slug": "product-return-form",
    "status": "publish",
    "type": "page",
    "link": "https:\/\/ingrilspa.com\/en\/product-return-form\/",
    "title": {
        "rendered": "Product return form"
    },
    "content": {
        "rendered": "<div data-elementor-type=\"wp-page\" data-elementor-id=\"875\" class=\"elementor elementor-875\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4631ed4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4631ed4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6080e28\" data-id=\"6080e28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df6bd4 elementor-widget elementor-widget-text-editor\" data-id=\"4df6bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f970-o1\" lang=\"lt-LT\" dir=\"ltr\" data-wpcf7-id=\"970\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/875#wpcf7-f970-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontakt\u0173 forma\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/875#wpcf7-f970-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"970\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"lt_LT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f970-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Name (required) <\/label><br \/>\nFirst<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span><br \/>\nLast<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n<\/p>\n<p><label> Order number (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"order-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"order-number\" \/><\/span> <\/label>\n<\/p>\n<p><label> Date of order (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-order\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" min=\"2022-10-05\" max=\"2023-12-31\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-order\" \/><\/span> <\/label>\n<\/p>\n<p><label> Phone number (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"+370\" value=\"\" type=\"number\" name=\"phone-number\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Name of the returned item (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"returned-item\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"returned-item\" \/><\/span> <\/label>\n<\/p>\n<p><label> Quantity (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"quantity\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"quantity\" \/><\/span> <\/label>\n<\/p>\n<p><label> Has the package been opened ? (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"been-opened\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"been-opened\"><option value=\"Taip\">Taip<\/option><option value=\"Ne\">Ne<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> Reasons for return (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> Add product photos (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"file-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-1\" \/><\/span> <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"file-2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-2\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"file-3\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-3\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6LdPO0AiAAAAAKLCUQVb_x4VEddtXNbjNWu_CTjK\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6LdPO0AiAAAAAKLCUQVb_x4VEddtXNbjNWu_CTjK\" frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>",
        "protected": false
    },
    "excerpt": {
        "rendered": "",
        "protected": false
    },
    "author": 1,
    "featured_media": 0,
    "parent": 0,
    "menu_order": 0,
    "comment_status": "closed",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "footnotes": ""
    },
    "class_list": [
        "post-875",
        "page",
        "type-page",
        "status-publish",
        "hentry"
    ],
    "aioseo_notices": [],
    "aioseo_head": "<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"mCOMrTItLfjwFVAT8q_XsEPEdCn5VQ3cnK3m3wzGn3E\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ingrilspa.com\/en\/product-return-form\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ingrilspa.com - IngrilSPA - \u017dvak\u0117s, Muilai, Levand\u0173 Puok\u0161t\u0117s, Nam\u0173 Kvapai\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Product return form - ingrilspa.com\" \/>\n\t\t<meta property=\"og:description\" content=\"Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ingrilspa.com\/en\/product-return-form\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ingrilspa.com\/wp-content\/uploads\/2026\/06\/Hero-icon.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ingrilspa.com\/wp-content\/uploads\/2026\/06\/Hero-icon.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1288\" \/>\n\t\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-22T21:10:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-29T20:12:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Levand-mergel-106857467813015\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ingril_knitting\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Product return form - ingrilspa.com\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ingril_knitting\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ingrilspa.com\/wp-content\/uploads\/2022\/09\/Ingril-SPA-logotipas_be_remelio_edited.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ingrilspa.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#listItem\",\"name\":\"Product return form\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#listItem\",\"position\":2,\"name\":\"Product return form\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/#organization\",\"name\":\"IngrilSPA\",\"description\":\"IngrilSPA - \\u017dvak\\u0117s, Muilai, Levand\\u0173 Puok\\u0161t\\u0117s, Nam\\u0173 Kvapai\",\"url\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/\",\"telephone\":\"+37066544741\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ingrilspa.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ingril-SPA-logotipas_be_remelio_edited.png\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#organizationLogo\",\"width\":325,\"height\":81},\"image\":{\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Levand-mergel-106857467813015\",\"https:\\\/\\\/twitter.com\\\/ingril_knitting\",\"https:\\\/\\\/www.instagram.com\\\/ingril_brand\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ingril_knitting\\\/ingril-spa\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#webpage\",\"url\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/\",\"name\":\"Product return form - ingrilspa.com\",\"description\":\"Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/product-return-form\\\/#breadcrumblist\"},\"datePublished\":\"2022-09-22T23:10:59+02:00\",\"dateModified\":\"2022-09-29T22:12:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/\",\"name\":\"ingrilspa.com\",\"description\":\"IngrilSPA - \\u017dvak\\u0117s, Muilai, Levand\\u0173 Puok\\u0161t\\u0117s, Nam\\u0173 Kvapai\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ingrilspa.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->",
    "aioseo_head_json": {
        "title": "Product return form - ingrilspa.com",
        "description": "Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)",
        "canonical_url": "https:\/\/ingrilspa.com\/en\/product-return-form\/",
        "robots": "max-image-preview:large",
        "keywords": "",
        "webmasterTools": {
            "google-site-verification": "mCOMrTItLfjwFVAT8q_XsEPEdCn5VQ3cnK3m3wzGn3E",
            "miscellaneous": ""
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#breadcrumblist",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "@id": "https:\/\/ingrilspa.com\/en#listItem",
                            "position": 1,
                            "name": "Home",
                            "item": "https:\/\/ingrilspa.com\/en",
                            "nextItem": {
                                "@type": "ListItem",
                                "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#listItem",
                                "name": "Product return form"
                            }
                        },
                        {
                            "@type": "ListItem",
                            "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#listItem",
                            "position": 2,
                            "name": "Product return form",
                            "previousItem": {
                                "@type": "ListItem",
                                "@id": "https:\/\/ingrilspa.com\/en#listItem",
                                "name": "Home"
                            }
                        }
                    ]
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/ingrilspa.com\/en\/#organization",
                    "name": "IngrilSPA",
                    "description": "IngrilSPA - \u017dvak\u0117s, Muilai, Levand\u0173 Puok\u0161t\u0117s, Nam\u0173 Kvapai",
                    "url": "https:\/\/ingrilspa.com\/en\/",
                    "telephone": "+37066544741",
                    "logo": {
                        "@type": "ImageObject",
                        "url": "https:\/\/ingrilspa.com\/wp-content\/uploads\/2022\/09\/Ingril-SPA-logotipas_be_remelio_edited.png",
                        "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#organizationLogo",
                        "width": 325,
                        "height": 81
                    },
                    "image": {
                        "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#organizationLogo"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/Levand-mergel-106857467813015",
                        "https:\/\/twitter.com\/ingril_knitting",
                        "https:\/\/www.instagram.com\/ingril_brand\/",
                        "https:\/\/www.pinterest.com\/ingril_knitting\/ingril-spa\/"
                    ]
                },
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#webpage",
                    "url": "https:\/\/ingrilspa.com\/en\/product-return-form\/",
                    "name": "Product return form - ingrilspa.com",
                    "description": "Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)",
                    "inLanguage": "en-US",
                    "isPartOf": {
                        "@id": "https:\/\/ingrilspa.com\/en\/#website"
                    },
                    "breadcrumb": {
                        "@id": "https:\/\/ingrilspa.com\/en\/product-return-form\/#breadcrumblist"
                    },
                    "datePublished": "2022-09-22T23:10:59+02:00",
                    "dateModified": "2022-09-29T22:12:46+02:00"
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/ingrilspa.com\/en\/#website",
                    "url": "https:\/\/ingrilspa.com\/en\/",
                    "name": "ingrilspa.com",
                    "description": "IngrilSPA - \u017dvak\u0117s, Muilai, Levand\u0173 Puok\u0161t\u0117s, Nam\u0173 Kvapai",
                    "inLanguage": "en-US",
                    "publisher": {
                        "@id": "https:\/\/ingrilspa.com\/en\/#organization"
                    }
                }
            ]
        },
        "og:locale": "en_US",
        "og:site_name": "ingrilspa.com - IngrilSPA - \u017dvak\u0117s, Muilai, Levand\u0173 Puok\u0161t\u0117s, Nam\u0173 Kvapai",
        "og:type": "article",
        "og:title": "Product return form - ingrilspa.com",
        "og:description": "Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)",
        "og:url": "https:\/\/ingrilspa.com\/en\/product-return-form\/",
        "og:image": "https:\/\/ingrilspa.com\/wp-content\/uploads\/2026\/06\/Hero-icon.jpg",
        "og:image:secure_url": "https:\/\/ingrilspa.com\/wp-content\/uploads\/2026\/06\/Hero-icon.jpg",
        "og:image:width": 1288,
        "og:image:height": 710,
        "article:published_time": "2022-09-22T21:10:59+00:00",
        "article:modified_time": "2022-09-29T20:12:46+00:00",
        "article:publisher": "https:\/\/www.facebook.com\/Levand-mergel-106857467813015",
        "twitter:card": "summary",
        "twitter:site": "@ingril_knitting",
        "twitter:title": "Product return form - ingrilspa.com",
        "twitter:description": "Name (required) First Last Order number (required) Date of order (required) Phone number (required) Email (required) Name of the returned item (required) Quantity (required) Has the package been opened ? (required) TaipNe Reasons for return (required) Add product photos (required)",
        "twitter:creator": "@ingril_knitting",
        "twitter:image": "https:\/\/ingrilspa.com\/wp-content\/uploads\/2022\/09\/Ingril-SPA-logotipas_be_remelio_edited.png"
    },
    "aioseo_meta_data": {
        "post_id": "875",
        "title": null,
        "description": null,
        "keywords": [],
        "keyphrases": {
            "focus": {
                "keyphrase": "",
                "score": 0,
                "analysis": {
                    "keyphraseInTitle": {
                        "score": 0,
                        "maxScore": 9,
                        "error": 1
                    }
                }
            },
            "additional": []
        },
        "primary_term": null,
        "canonical_url": null,
        "og_title": null,
        "og_description": null,
        "og_object_type": "default",
        "og_image_type": "default",
        "og_image_url": null,
        "og_image_width": null,
        "og_image_height": null,
        "og_image_custom_url": null,
        "og_image_custom_fields": null,
        "og_video": "",
        "og_custom_url": null,
        "og_article_section": null,
        "og_article_tags": [],
        "twitter_use_og": false,
        "twitter_card": "default",
        "twitter_image_type": "default",
        "twitter_image_url": null,
        "twitter_image_custom_url": null,
        "twitter_image_custom_fields": null,
        "twitter_title": null,
        "twitter_description": null,
        "schema": {
            "blockGraphs": [],
            "customGraphs": [],
            "default": {
                "data": {
                    "Article": [],
                    "Course": [],
                    "Dataset": [],
                    "FAQPage": [],
                    "Movie": [],
                    "Person": [],
                    "Product": [],
                    "ProductReview": [],
                    "Car": [],
                    "Recipe": [],
                    "Service": [],
                    "SoftwareApplication": [],
                    "WebPage": []
                },
                "graphName": "",
                "isEnabled": true
            },
            "graphs": []
        },
        "schema_type": "default",
        "schema_type_options": null,
        "pillar_content": false,
        "robots_default": true,
        "robots_noindex": false,
        "robots_noarchive": false,
        "robots_nosnippet": false,
        "robots_nofollow": false,
        "robots_noimageindex": false,
        "robots_noodp": false,
        "robots_notranslate": false,
        "robots_max_snippet": "-1",
        "robots_max_videopreview": "-1",
        "robots_max_imagepreview": "large",
        "priority": null,
        "frequency": "default",
        "local_seo": null,
        "breadcrumb_settings": null,
        "limit_modified_date": false,
        "ai": null,
        "created": "2022-09-22 21:11:01",
        "updated": "2025-06-03 23:17:37",
        "seo_analyzer_scan_date": null
    },
    "aioseo_breadcrumb": "<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ingrilspa.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProduct return form\n\t\t<\/span><\/div>",
    "aioseo_breadcrumb_json": [
        {
            "label": "Home",
            "link": "https:\/\/ingrilspa.com\/en"
        },
        {
            "label": "Product return form",
            "link": "https:\/\/ingrilspa.com\/en\/product-return-form\/"
        }
    ],
    "_links": {
        "self": [
            {
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/pages\/875",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/pages"
            }
        ],
        "about": [
            {
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/types\/page"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/users\/1"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/comments?post=875"
            }
        ],
        "version-history": [
            {
                "count": 5,
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/pages\/875\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 978,
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/pages\/875\/revisions\/978"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/ingrilspa.com\/en\/wp-json\/wp\/v2\/media?parent=875"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}